{"id":964,"date":"2024-04-08T17:47:17","date_gmt":"2024-04-08T17:47:17","guid":{"rendered":"https:\/\/maurifer.com\/?post_type=product&#038;p=964"},"modified":"2025-10-21T07:47:37","modified_gmt":"2025-10-21T07:47:37","slug":"tole-galva-ondulee-prelaque-bleu-045mm","status":"publish","type":"product","link":"https:\/\/maurifer.com\/ar\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/","title":{"rendered":"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dimensions<\/p>\n<p>Long = 5,8m<\/p>\n<p>Larg = 0,9m<\/p>","protected":false},"featured_media":965,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[94],"product_tag":[],"class_list":{"0":"post-964","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tole-galvanise","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurifer.com\/ar\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER\" \/>\n<meta property=\"og:description\" content=\"Dimensions  Long = 5,8m  Larg = 0,9m\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurifer.com\/ar\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/\" \/>\n<meta property=\"og:site_name\" content=\"MAURIFER\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T07:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u0629 \u0648\u0627\u062d\u062f\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/\",\"url\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/\",\"name\":\"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER\",\"isPartOf\":{\"@id\":\"https:\/\/maurifer.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp\",\"datePublished\":\"2024-04-08T17:47:17+00:00\",\"dateModified\":\"2025-10-21T07:47:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage\",\"url\":\"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp\",\"contentUrl\":\"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp\",\"width\":550,\"height\":547},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/maurifer.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/maurifer.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/maurifer.com\/#website\",\"url\":\"https:\/\/maurifer.com\/\",\"name\":\"MAURIFER\",\"description\":\"Online Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/maurifer.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurifer.com\/ar\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/","og_locale":"ar_AR","og_type":"article","og_title":"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER","og_description":"Dimensions  Long = 5,8m  Larg = 0,9m","og_url":"https:\/\/maurifer.com\/ar\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/","og_site_name":"MAURIFER","article_modified_time":"2025-10-21T07:47:37+00:00","og_image":[{"width":550,"height":547,"url":"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u0629 \u0648\u0627\u062d\u062f\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/","url":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/","name":"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm - MAURIFER","isPartOf":{"@id":"https:\/\/maurifer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage"},"image":{"@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage"},"thumbnailUrl":"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp","datePublished":"2024-04-08T17:47:17+00:00","dateModified":"2025-10-21T07:47:37+00:00","breadcrumb":{"@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#primaryimage","url":"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp","contentUrl":"https:\/\/maurifer.com\/wp-content\/uploads\/2024\/04\/Galvanized-Corrugated-Roofing-Steel-Sheet.webp","width":550,"height":547},{"@type":"BreadcrumbList","@id":"https:\/\/maurifer.com\/product\/tole-galva-ondulee-prelaque-bleu-045mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maurifer.com\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/maurifer.com\/shop\/"},{"@type":"ListItem","position":3,"name":"T\u00f4le galva ondul\u00e9e pr\u00e9laqu\u00e9 bleu 0,35mm"}]},{"@type":"WebSite","@id":"https:\/\/maurifer.com\/#website","url":"https:\/\/maurifer.com\/","name":"MAURIFER","description":"Online Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maurifer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/product\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/comments?post=964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/product_brand?post=964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/product_cat?post=964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maurifer.com\/ar\/wp-json\/wp\/v2\/product_tag?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}